{"id":95865,"date":"2023-03-17T19:06:09","date_gmt":"2023-03-17T18:06:09","guid":{"rendered":"https:\/\/watchdeluxe.it\/prodotto\/longines-conquest-v-h-p-41-mm-ref-l37162766\/"},"modified":"2026-04-02T12:06:15","modified_gmt":"2026-04-02T10:06:15","slug":"longines-conquest-v-h-p-41-mm-ref-l37162766","status":"publish","type":"product","link":"https:\/\/watchdeluxe.it\/nl\/prodotto\/longines-conquest-v-h-p-41-mm-ref-l37162766\/","title":{"rendered":"LONGINES CONQUEST V.H.P. 41 MM REF. L37162766"},"content":{"rendered":"<p>LONGINES CONQUEST V.H.P. 41 MM REF. L37162766<\/p>\n<table class=\"data-table\">\n<tbody>\n<tr class=\"odd\">\n<td class=\"spec-name\">Merk<\/td>\n<td class=\"spec-value\">Longines<\/td>\n<\/tr>\n<tr class=\"even\">\n<td class=\"spec-name\">Lijn<\/td>\n<td class=\"spec-value\">CONQUEST<\/td>\n<\/tr>\n<tr class=\"odd\">\n<td class=\"spec-name\">Type uurwerk<\/td>\n<td class=\"spec-value\">ALLEEN TIJD<\/td>\n<\/tr>\n<tr class=\"even\">\n<td class=\"spec-name\">Beweging<\/td>\n<td class=\"spec-value\">KWARTZ<\/td>\n<\/tr>\n<tr class=\"odd\">\n<td class=\"spec-name\">Datum<\/td>\n<td class=\"spec-value\">EEUWIGE KALENDER<\/td>\n<\/tr>\n<tr class=\"even\">\n<td class=\"spec-name\">Vorm<\/td>\n<td class=\"spec-value\">RONDE<\/td>\n<\/tr>\n<tr class=\"odd\">\n<td class=\"spec-name\">Maat<\/td>\n<td class=\"spec-value\">41 MM<\/td>\n<\/tr>\n<tr class=\"even\">\n<td class=\"spec-name\">Materiaal<\/td>\n<td class=\"spec-value\">PVD<\/td>\n<\/tr>\n<tr class=\"odd\">\n<td class=\"spec-name\">Wijzerplaat<\/td>\n<td class=\"spec-value\">WIT<\/td>\n<\/tr>\n<tr class=\"even\">\n<td class=\"spec-name\">Armband<\/td>\n<td class=\"spec-value\">PVD<\/td>\n<\/tr>\n<tr class=\"odd\">\n<td class=\"spec-name\">Waterbestendigheid<\/td>\n<td class=\"spec-value\">50 M<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n","protected":false},"excerpt":{"rendered":"<p>LONGINES CONQUEST V.H.P. 41 MM REF. L37162766 Merk Longines Lijn CONQUEST Type uurwerk ALLEEN TIJD Beweging KWARTZ Datum EEUWIGE KALENDER Vorm RONDE Maat 41 MM Materiaal PVD Wijzerplaat WIT Armband PVD Waterbestendigheid 50 M<\/p>\n","protected":false},"featured_media":205981,"template":"","meta":{"advanced_seo_description":"","jetpack_seo_html_title":"","jetpack_seo_noindex":false,"jetpack_seo_schema_type":""},"product_brand":[],"product_cat":[4269],"product_tag":[4305,4364,4283],"berocket_brand":[],"woo-feed-brand":[],"class_list":["post-95865","product","type-product","status-publish","has-post-thumbnail","product_cat-longines-nl","product_tag-hydroconquest-nl","product_tag-kwarts","product_tag-verovering","first","instock","sale","taxable","shipping-taxable","purchasable","product-type-simple"],"bundled_by":[],"bundle_stock_status":"instock","bundle_stock_quantity":1,"bundle_virtual":false,"bundle_layout":"","bundle_add_to_cart_form_location":"","bundle_editable_in_cart":false,"bundle_sold_individually_context":"","bundle_item_grouping":"","bundle_min_size":"","bundle_max_size":"","bundle_price":[],"bundled_items":[],"bundle_sell_ids":[],"group_of_quantity":0,"min_quantity":0,"max_quantity":"","exclude_order_quantity_value_rules":"no","exclude_category_quantity_rules":"no","combine_variations":"no","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/watchdeluxe.it\/nl\/wp-json\/wp\/v2\/product\/95865","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/watchdeluxe.it\/nl\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/watchdeluxe.it\/nl\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/watchdeluxe.it\/nl\/wp-json\/wp\/v2\/media\/205981"}],"wp:attachment":[{"href":"https:\/\/watchdeluxe.it\/nl\/wp-json\/wp\/v2\/media?parent=95865"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/watchdeluxe.it\/nl\/wp-json\/wp\/v2\/product_brand?post=95865"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/watchdeluxe.it\/nl\/wp-json\/wp\/v2\/product_cat?post=95865"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/watchdeluxe.it\/nl\/wp-json\/wp\/v2\/product_tag?post=95865"},{"taxonomy":"berocket_brand","embeddable":true,"href":"https:\/\/watchdeluxe.it\/nl\/wp-json\/wp\/v2\/berocket_brand?post=95865"},{"taxonomy":"woo-feed-brand","embeddable":true,"href":"https:\/\/watchdeluxe.it\/nl\/wp-json\/wp\/v2\/woo-feed-brand?post=95865"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}