{"id":92088,"date":"2024-05-31T15:35:33","date_gmt":"2024-05-31T13:35:33","guid":{"rendered":"https:\/\/watchdeluxe.it\/prodotto\/baume-mercier-baume-42-mm-ref-m0a10637\/"},"modified":"2026-04-06T08:39:45","modified_gmt":"2026-04-06T06:39:45","slug":"baume-mercier-baume-42-mm-ref-m0a10637","status":"publish","type":"product","link":"https:\/\/watchdeluxe.it\/fr\/prodotto\/baume-mercier-baume-42-mm-ref-m0a10637\/","title":{"rendered":"Baume &amp; Mercier Baume 42 Mm Ref. M0A10637"},"content":{"rendered":"<p>Baume &amp; Mercier Baume 42 Mm Ref. M0A10637<\/p>\n<div class=\"overview\">\n<div class=\"short-description\">Montre Baume ronde avec couronne \u00e0 12 heures, cornes articul\u00e9es en acier PVD noir et syst\u00e8me de bracelet \u00e0 boutons interchangeables. Elle pr\u00e9sente un cadran laqu\u00e9 bleu orn\u00e9 d&#8217;un disque de phase de lune exclusif. Il est accompagn\u00e9 d&#8217;un bracelet en coton bleu.<\/div>\n<p>&nbsp;<\/p>\n<div class=\"product-collateral\">\n<div class=\"product-specs-box\">\n<div class=\"title\"><strong>D\u00e9tails du produit<\/strong><\/div>\n<div class=\"table-wrapper\">\n<table class=\"data-table\">\n<colgroup>\n<col width=\"25%\">\n<col> <\/colgroup>\n<tbody>\n<tr class=\"odd\">\n<td class=\"spec-name\">Ligne<\/td>\n<td class=\"spec-value\">BAUME<\/td>\n<\/tr>\n<tr class=\"even\">\n<td class=\"spec-name\">Complication<\/td>\n<td class=\"spec-value\">PHASES DE LUNE<\/td>\n<\/tr>\n<tr class=\"odd\">\n<td class=\"spec-name\">Mouvement<\/td>\n<td class=\"spec-value\">QUARTZ<\/td>\n<\/tr>\n<tr class=\"even\">\n<td class=\"spec-name\">Forme<\/td>\n<td class=\"spec-value\">ROND<\/td>\n<\/tr>\n<tr class=\"odd\">\n<td class=\"spec-name\">Taille<\/td>\n<td class=\"spec-value\">42 MM<\/td>\n<\/tr>\n<tr class=\"even\">\n<td class=\"spec-name\">Mat\u00e9riau du bo\u00eetier<\/td>\n<td class=\"spec-value\">Acier<\/td>\n<\/tr>\n<tr class=\"odd\">\n<td class=\"spec-name\">Cadran<\/td>\n<td class=\"spec-value\">BLEU<\/td>\n<\/tr>\n<tr class=\"even\">\n<td class=\"spec-name\">Bracelet<\/td>\n<td class=\"spec-value\">COTON<\/td>\n<\/tr>\n<tr class=\"odd\">\n<td class=\"spec-name\">R\u00e9sistance \u00e0 l&#8217;eau<\/td>\n<td class=\"spec-value\">30 M<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Baume &amp; Mercier Baume 42 Mm Ref. M0A10637 Montre Baume ronde avec couronne \u00e0 12 heures, cornes articul\u00e9es en acier PVD noir et syst\u00e8me de bracelet \u00e0 boutons interchangeables. Elle pr\u00e9sente un cadran laqu\u00e9 bleu orn\u00e9 d&#8217;un disque de phase de lune exclusif. Il est accompagn\u00e9 d&#8217;un bracelet en coton bleu. &nbsp; D\u00e9tails du produit [&hellip;]<\/p>\n","protected":false},"featured_media":203579,"template":"","meta":{"advanced_seo_description":"","jetpack_seo_html_title":"","jetpack_seo_noindex":false,"jetpack_seo_schema_type":""},"product_brand":[],"product_cat":[5515],"product_tag":[2652],"berocket_brand":[],"woo-feed-brand":[],"class_list":["post-92088","product","type-product","status-publish","has-post-thumbnail","product_cat-baume-mercier-fr2","product_tag-baume-fr","first","instock","sale","taxable","shipping-taxable","purchasable","product-type-simple"],"bundled_by":[],"bundle_stock_status":"instock","bundle_stock_quantity":1,"bundle_virtual":false,"bundle_layout":"","bundle_add_to_cart_form_location":"","bundle_editable_in_cart":false,"bundle_sold_individually_context":"","bundle_item_grouping":"","bundle_min_size":"","bundle_max_size":"","bundle_price":[],"bundled_items":[],"bundle_sell_ids":[],"group_of_quantity":0,"min_quantity":0,"max_quantity":"","exclude_order_quantity_value_rules":"no","exclude_category_quantity_rules":"no","combine_variations":"no","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/watchdeluxe.it\/fr\/wp-json\/wp\/v2\/product\/92088","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/watchdeluxe.it\/fr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/watchdeluxe.it\/fr\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/watchdeluxe.it\/fr\/wp-json\/wp\/v2\/media\/203579"}],"wp:attachment":[{"href":"https:\/\/watchdeluxe.it\/fr\/wp-json\/wp\/v2\/media?parent=92088"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/watchdeluxe.it\/fr\/wp-json\/wp\/v2\/product_brand?post=92088"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/watchdeluxe.it\/fr\/wp-json\/wp\/v2\/product_cat?post=92088"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/watchdeluxe.it\/fr\/wp-json\/wp\/v2\/product_tag?post=92088"},{"taxonomy":"berocket_brand","embeddable":true,"href":"https:\/\/watchdeluxe.it\/fr\/wp-json\/wp\/v2\/berocket_brand?post=92088"},{"taxonomy":"woo-feed-brand","embeddable":true,"href":"https:\/\/watchdeluxe.it\/fr\/wp-json\/wp\/v2\/woo-feed-brand?post=92088"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}