{"id":68267,"date":"2023-03-22T10:37:00","date_gmt":"2023-03-22T09:37:00","guid":{"rendered":"https:\/\/watchdeluxe.it\/prodotto\/baume-mercier-mod-promesse-ref-m0a10185\/"},"modified":"2026-03-27T14:06:51","modified_gmt":"2026-03-27T13:06:51","slug":"baume-mercier-mod-promesse-ref-m0a10185","status":"publish","type":"product","link":"https:\/\/watchdeluxe.it\/fr\/prodotto\/baume-mercier-mod-promesse-ref-m0a10185\/","title":{"rendered":"BAUME &amp; MERCIER MOD. PROMESSE REF. M0A10185"},"content":{"rendered":"<p>BAUME &amp; MERCIER MOD. PROMESSE REF. 10185<\/p>\n<div class=\"text_box_large\">\n<p>El\u00e9gante et raffin\u00e9e, cette montre en acier d&#8217;un diam\u00e8tre de 30 mm et dot\u00e9e d&#8217;un bracelet en veau noir se distingue par son design sobre et d\u00e9licat, rehauss\u00e9 par une lunette ovale noire satin\u00e9e. Ce dernier d\u00e9tail met particuli\u00e8rement en valeur le cadran argent\u00e9 avec son drap\u00e9 guilloch\u00e9.<\/p>\n<\/div>\n<div class=\"text_box_large\">\n<h5>Sp\u00e9cifications<\/h5>\n<div class=\"specifiche_l\">\n<div class=\"caratteristica_l\">\n<div class=\"etichetta\">Fonctions<\/div>\n<div class=\"valore\"><\/div>\n<\/div>\n<div class=\"caratteristica_l\">\n<div class=\"etichetta\">Mouvement<\/div>\n<div class=\"valore\">Quartz<\/div>\n<\/div>\n<div class=\"caratteristica_l\">\n<div class=\"etichetta\">Genre<\/div>\n<div class=\"valore\"><\/div>\n<\/div>\n<div class=\"caratteristica_l\">\n<div class=\"etichetta\">Diamants<\/div>\n<div class=\"valore\">Sans diamants<\/div>\n<\/div>\n<\/div>\n<div class=\"specifiche_l\">\n<div class=\"caratteristica_r\">\n<div class=\"etichetta\">Bracelet\/Strap<\/div>\n<div class=\"valore\">Cuir<\/div>\n<\/div>\n<div class=\"caratteristica_r\">\n<div class=\"etichetta\">Calibre<\/div>\n<div class=\"valore\"><\/div>\n<\/div>\n<div class=\"caratteristica_r\">\n<div class=\"etichetta\">Cadran<\/div>\n<div class=\"valore\">Clair<\/div>\n<\/div>\n<div class=\"caratteristica_r\">\n<div class=\"etichetta\">Cas<\/div>\n<div class=\"valore\"><\/div>\n<\/div>\n<div class=\"caratteristica_r\">\n<div class=\"etichetta\">Bo\u00eetier mm<\/div>\n<div class=\"valore\">&#8211;<\/div>\n<\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>BAUME &amp; MERCIER MOD. PROMESSE REF. 10185 El\u00e9gante et raffin\u00e9e, cette montre en acier d&#8217;un diam\u00e8tre de 30 mm et dot\u00e9e d&#8217;un bracelet en veau noir se distingue par son design sobre et d\u00e9licat, rehauss\u00e9 par une lunette ovale noire satin\u00e9e. Ce dernier d\u00e9tail met particuli\u00e8rement en valeur le cadran argent\u00e9 avec son drap\u00e9 guilloch\u00e9. [&hellip;]<\/p>\n","protected":false},"featured_media":62732,"template":"","meta":{"advanced_seo_description":"","jetpack_seo_html_title":"","jetpack_seo_noindex":false,"jetpack_seo_schema_type":""},"product_brand":[],"product_cat":[5515],"product_tag":[2625],"berocket_brand":[],"woo-feed-brand":[],"class_list":["post-68267","product","type-product","status-publish","has-post-thumbnail","product_cat-baume-mercier-fr2","product_tag-promesses","first","instock","sale","taxable","shipping-taxable","purchasable","product-type-simple"],"bundled_by":[],"bundle_stock_status":"instock","bundle_stock_quantity":1,"bundle_virtual":false,"bundle_layout":"","bundle_add_to_cart_form_location":"","bundle_editable_in_cart":false,"bundle_sold_individually_context":"","bundle_item_grouping":"","bundle_min_size":"","bundle_max_size":"","bundle_price":[],"bundled_items":[],"bundle_sell_ids":[],"group_of_quantity":0,"min_quantity":0,"max_quantity":"","exclude_order_quantity_value_rules":"no","exclude_category_quantity_rules":"no","combine_variations":"no","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/watchdeluxe.it\/fr\/wp-json\/wp\/v2\/product\/68267","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/watchdeluxe.it\/fr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/watchdeluxe.it\/fr\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/watchdeluxe.it\/fr\/wp-json\/wp\/v2\/media\/62732"}],"wp:attachment":[{"href":"https:\/\/watchdeluxe.it\/fr\/wp-json\/wp\/v2\/media?parent=68267"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/watchdeluxe.it\/fr\/wp-json\/wp\/v2\/product_brand?post=68267"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/watchdeluxe.it\/fr\/wp-json\/wp\/v2\/product_cat?post=68267"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/watchdeluxe.it\/fr\/wp-json\/wp\/v2\/product_tag?post=68267"},{"taxonomy":"berocket_brand","embeddable":true,"href":"https:\/\/watchdeluxe.it\/fr\/wp-json\/wp\/v2\/berocket_brand?post=68267"},{"taxonomy":"woo-feed-brand","embeddable":true,"href":"https:\/\/watchdeluxe.it\/fr\/wp-json\/wp\/v2\/woo-feed-brand?post=68267"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}