{"id":76557,"date":"2023-03-17T18:41:29","date_gmt":"2023-03-17T17:41:29","guid":{"rendered":"https:\/\/watchdeluxe.it\/prodotto\/mido-multifort-dual-time-ref-m0384291104100\/"},"modified":"2026-04-06T06:57:41","modified_gmt":"2026-04-06T04:57:41","slug":"mido-multifort-dual-time-ref-m0384291104100","status":"publish","type":"product","link":"https:\/\/watchdeluxe.it\/es\/prodotto\/mido-multifort-dual-time-ref-m0384291104100\/","title":{"rendered":"Mido Multifort Dual Time ref. M0384291104100"},"content":{"rendered":"<p>Mido Multifort Dual Time ref. M0384291104100<\/p>\n<dl class=\"data-sheet\">\n<dt class=\"name\">Marca<\/dt>\n<dd class=\"value\">Mido<\/dd>\n<dt class=\"name\">Categor\u00eda<\/dt>\n<dd class=\"value\">Relojes<\/dd>\n<dt class=\"name\">G\u00e9nero<\/dt>\n<dd class=\"value\">Hombre<\/dd>\n<dt class=\"name\">Formulario<\/dt>\n<dd class=\"value\">Redondo<\/dd>\n<dt class=\"name\">Movimiento<\/dt>\n<dd class=\"value\">Mec\u00e1nica autom\u00e1tica<\/dd>\n<dt class=\"name\">Resistente al agua<\/dt>\n<dd class=\"value\">100 m (10 ATM)<\/dd>\n<dt class=\"name\">Dimensiones de la caja<\/dt>\n<dd class=\"value\">42 mm<\/dd>\n<dt class=\"name\">Material del malet\u00edn<\/dt>\n<dd class=\"value\">Acero inoxidable<\/dd>\n<dt class=\"name\">Color de la caja<\/dt>\n<dd class=\"value\">Plata<\/dd>\n<dt class=\"name\">Material de la correa<\/dt>\n<dd class=\"value\">Acero inoxidable<\/dd>\n<dt class=\"name\">Color de la correa principal<\/dt>\n<dd class=\"value\">Plata<\/dd>\n<dt class=\"name\">Funciones<\/dt>\n<dd class=\"value\">Fechador<\/dd>\n<dt class=\"name\">Acabado<\/dt>\n<dd class=\"value\">Raso<\/dd>\n<dt class=\"name\">Color de la esfera<\/dt>\n<dd class=\"value\">Azul<\/dd>\n<dt class=\"name\">Garant\u00eda<\/dt>\n<dd class=\"value\">2 a\u00f1os + 1 a\u00f1o<\/dd>\n<dt class=\"name\">Embalaje<\/dt>\n<dd class=\"value\">Caja original<\/dd>\n<\/dl>\n","protected":false},"excerpt":{"rendered":"<p>Mido Multifort Dual Time ref. M0384291104100 Marca Mido Categor\u00eda Relojes G\u00e9nero Hombre Formulario Redondo Movimiento Mec\u00e1nica autom\u00e1tica Resistente al agua 100 m (10 ATM) Dimensiones de la caja 42 mm Material del malet\u00edn Acero inoxidable Color de la caja Plata Material de la correa Acero inoxidable Color de la correa principal Plata Funciones Fechador Acabado [&hellip;]<\/p>\n","protected":false},"featured_media":206930,"template":"","meta":{"advanced_seo_description":"","jetpack_seo_html_title":"","jetpack_seo_noindex":false,"jetpack_seo_schema_type":""},"product_brand":[],"product_cat":[2940],"product_tag":[2949],"berocket_brand":[],"woo-feed-brand":[],"class_list":["post-76557","product","type-product","status-publish","has-post-thumbnail","product_cat-mido-es","product_tag-multifort-es","first","instock","sale","taxable","shipping-taxable","purchasable","product-type-simple"],"bundled_by":[],"bundle_stock_status":"instock","bundle_stock_quantity":1,"bundle_virtual":false,"bundle_layout":"","bundle_add_to_cart_form_location":"","bundle_editable_in_cart":false,"bundle_sold_individually_context":"","bundle_item_grouping":"","bundle_min_size":"","bundle_max_size":"","bundle_price":[],"bundled_items":[],"bundle_sell_ids":[],"group_of_quantity":0,"min_quantity":0,"max_quantity":"","exclude_order_quantity_value_rules":"no","exclude_category_quantity_rules":"no","combine_variations":"no","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/watchdeluxe.it\/es\/wp-json\/wp\/v2\/product\/76557","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/watchdeluxe.it\/es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/watchdeluxe.it\/es\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/watchdeluxe.it\/es\/wp-json\/wp\/v2\/media\/206930"}],"wp:attachment":[{"href":"https:\/\/watchdeluxe.it\/es\/wp-json\/wp\/v2\/media?parent=76557"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/watchdeluxe.it\/es\/wp-json\/wp\/v2\/product_brand?post=76557"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/watchdeluxe.it\/es\/wp-json\/wp\/v2\/product_cat?post=76557"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/watchdeluxe.it\/es\/wp-json\/wp\/v2\/product_tag?post=76557"},{"taxonomy":"berocket_brand","embeddable":true,"href":"https:\/\/watchdeluxe.it\/es\/wp-json\/wp\/v2\/berocket_brand?post=76557"},{"taxonomy":"woo-feed-brand","embeddable":true,"href":"https:\/\/watchdeluxe.it\/es\/wp-json\/wp\/v2\/woo-feed-brand?post=76557"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}