{"id":124481,"date":"2025-11-05T15:21:27","date_gmt":"2025-11-05T14:21:27","guid":{"rendered":"https:\/\/watchdeluxe.it\/prodotto\/estuche-para-8-montblanc-meisterstuck-ref-199337\/"},"modified":"2025-11-05T15:21:27","modified_gmt":"2025-11-05T14:21:27","slug":"estuche-para-8-montblanc-meisterstuck-ref-199337","status":"publish","type":"product","link":"https:\/\/watchdeluxe.it\/es\/prodotto\/estuche-para-8-montblanc-meisterstuck-ref-199337\/","title":{"rendered":"Estuche para 8 Montblanc Meisterst\u00fcck ref. 199337"},"content":{"rendered":"<p>Estuche para 8 Montblanc Meisterst\u00fcck ref. 199337<\/p>\n<ul>\n<li data-hveid=\"CAQQAA\" data-complete=\"true\" data-sae=\"\"><span class=\"T286Pc\" data-sfc-cp=\"\" data-complete=\"true\"><strong class=\"Yjhzub\" data-complete=\"true\">Producto<\/strong>: Estuche para 8 plumas Montblanc.<\/span><\/li>\n<li data-hveid=\"CAQQAQ\" data-complete=\"true\" data-sae=\"\"><span class=\"T286Pc\" data-sfc-cp=\"\" data-complete=\"true\"><strong class=\"Yjhzub\" data-complete=\"true\">Colecci\u00f3n<\/strong>: Meisterst\u00fcck.<\/span><\/li>\n<li data-hveid=\"CAQQAg\" data-complete=\"true\" data-sae=\"\"><span class=\"T286Pc\" data-sfc-cp=\"\" data-complete=\"true\"><strong class=\"Yjhzub\" data-complete=\"true\">Material<\/strong>: Piel de becerro.<\/span><\/li>\n<li data-hveid=\"CAQQAw\" data-complete=\"true\" data-sae=\"\"><span class=\"T286Pc\" data-sfc-cp=\"\" data-complete=\"true\"><strong class=\"Yjhzub\" data-complete=\"true\">Color<\/strong>: Negro.<\/span><\/li>\n<li data-hveid=\"CAQQBA\" data-complete=\"true\" data-sae=\"\"><span class=\"T286Pc\" data-sfc-cp=\"\" data-complete=\"true\"><strong class=\"Yjhzub\" data-complete=\"true\">Capacidad<\/strong>: Puede contener hasta 8 art\u00edculos de escritura del tama\u00f1o de la colecci\u00f3n Classique o LeGrand.<\/span><\/li>\n<li data-hveid=\"CAQQBQ\" data-complete=\"true\" data-sae=\"\"><span class=\"T286Pc\" data-sfc-cp=\"\" data-complete=\"true\"><strong class=\"Yjhzub\" data-complete=\"true\">Dimensiones<\/strong>: 180 x 20 x 160 mm,  <\/span><\/li>\n<li data-hveid=\"CAQQBw\" data-complete=\"true\" data-sae=\"\"><span class=\"T286Pc\" data-sfc-cp=\"\" data-complete=\"true\"><strong class=\"Yjhzub\" data-complete=\"true\">Cierre<\/strong>: Equipado con una solapa para proteger con seguridad los instrumentos.<\/span><\/li>\n<li data-hveid=\"CAQQCA\" data-complete=\"true\" data-sae=\"\"><span class=\"T286Pc\" data-sfc-cp=\"\" data-complete=\"true\"><strong class=\"Yjhzub\" data-complete=\"true\">Estilo<\/strong>: Elegante y funcional<\/span><\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Estuche para 8 Montblanc Meisterst\u00fcck ref. 199337 Producto: Estuche para 8 plumas Montblanc. Colecci\u00f3n: Meisterst\u00fcck. Material: Piel de becerro. Color: Negro. Capacidad: Puede contener hasta 8 art\u00edculos de escritura del tama\u00f1o de la colecci\u00f3n Classique o LeGrand. Dimensiones: 180 x 20 x 160 mm, Cierre: Equipado con una solapa para proteger con seguridad los instrumentos. [&hellip;]<\/p>\n","protected":false},"featured_media":124465,"template":"","meta":{"advanced_seo_description":"","jetpack_seo_html_title":"","jetpack_seo_noindex":false,"jetpack_seo_schema_type":""},"product_brand":[],"product_cat":[2247],"product_tag":[4580],"berocket_brand":[],"woo-feed-brand":[],"class_list":["post-124481","product","type-product","status-publish","has-post-thumbnail","product_cat-montblanc-es","product_tag-portaboligrafos","first","instock","sale","taxable","shipping-taxable","purchasable","product-type-simple"],"bundled_by":[],"bundle_stock_status":"instock","bundle_stock_quantity":1,"bundle_virtual":false,"bundle_layout":"","bundle_add_to_cart_form_location":"","bundle_editable_in_cart":false,"bundle_sold_individually_context":"","bundle_item_grouping":"","bundle_min_size":"","bundle_max_size":"","bundle_price":[],"bundled_items":[],"bundle_sell_ids":[],"group_of_quantity":0,"min_quantity":0,"max_quantity":"","exclude_order_quantity_value_rules":"no","exclude_category_quantity_rules":"no","combine_variations":"no","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/watchdeluxe.it\/es\/wp-json\/wp\/v2\/product\/124481","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/watchdeluxe.it\/es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/watchdeluxe.it\/es\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/watchdeluxe.it\/es\/wp-json\/wp\/v2\/media\/124465"}],"wp:attachment":[{"href":"https:\/\/watchdeluxe.it\/es\/wp-json\/wp\/v2\/media?parent=124481"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/watchdeluxe.it\/es\/wp-json\/wp\/v2\/product_brand?post=124481"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/watchdeluxe.it\/es\/wp-json\/wp\/v2\/product_cat?post=124481"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/watchdeluxe.it\/es\/wp-json\/wp\/v2\/product_tag?post=124481"},{"taxonomy":"berocket_brand","embeddable":true,"href":"https:\/\/watchdeluxe.it\/es\/wp-json\/wp\/v2\/berocket_brand?post=124481"},{"taxonomy":"woo-feed-brand","embeddable":true,"href":"https:\/\/watchdeluxe.it\/es\/wp-json\/wp\/v2\/woo-feed-brand?post=124481"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}