{"id":123607,"date":"2025-11-03T17:25:00","date_gmt":"2025-11-03T16:25:00","guid":{"rendered":"https:\/\/watchdeluxe.it\/prodotto\/omega-seamaster-aqua-terra-150m-ref-220-32-38-20-03-001\/"},"modified":"2026-08-22T03:04:47","modified_gmt":"2026-08-22T01:04:47","slug":"omega-seamaster-aqua-terra-150m-ref-220-32-38-20-03-001","status":"publish","type":"product","link":"https:\/\/watchdeluxe.it\/es\/prodotto\/omega-seamaster-aqua-terra-150m-ref-220-32-38-20-03-001\/","title":{"rendered":"Omega seamaster aqua terra 150m ref. 220.32.38.20.03.001"},"content":{"rendered":"<p>Omega Seamaster Aqua terra 150m ref. 220.32.38.20.03.001<\/p>\n<ul>\n<li><span class=\"T286Pc\" data-sfc-cp=\"  data-complete=\"><strong class=\"Yjhzub\" data-complete=\"true\">Material de la caja:<\/strong> Acero inoxidable<\/span><\/li>\n<li><span class=\"T286Pc\" data-sfc-cp=\"  data-complete=\"><strong class=\"Yjhzub\" data-complete=\"true\">Di\u00e1metro de la caja:<\/strong> 38 mm<\/span><\/li>\n<li><span class=\"T286Pc\" data-sfc-cp=\"  data-complete=\"><strong class=\"Yjhzub\" data-complete=\"true\">Material del bisel:<\/strong> Cer\u00e1mica negra cepillada<\/span><\/li>\n<li><span class=\"T286Pc\" data-sfc-cp=\"  data-complete=\"><strong class=\"Yjhzub\" data-complete=\"true\">Esfera:<\/strong> Turquesa lacada con efecto sombreado (turquesa en el centro oscureci\u00e9ndose hacia los bordes)<\/span><\/li>\n<li><span class=\"T286Pc\" data-sfc-cp=\"  data-complete=\"><strong class=\"Yjhzub\" data-complete=\"true\">Correa:<\/strong> Caucho negro integrado con pespuntes turquesa y cierre desplegable de acero<\/span><\/li>\n<li><span class=\"T286Pc\" data-sfc-cp=\"  data-complete=\"><strong class=\"Yjhzub\" data-complete=\"true\">Movimiento:<\/strong> OMEGA Co-Axial Master Chronometer Calibre 8800 autom\u00e1tico, certificado METAS<\/span><\/li>\n<li><span class=\"T286Pc\" data-sfc-cp=\"  data-complete=\"><strong class=\"Yjhzub\" data-complete=\"true\">Resistencia al agua:<\/strong> 15 bares (150 metros \/ 500 pies)<\/span><\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Omega Seamaster Aqua terra 150m ref. 220.32.38.20.03.001 Material de la caja: Acero inoxidable Di\u00e1metro de la caja: 38 mm Material del bisel: Cer\u00e1mica negra cepillada Esfera: Turquesa lacada con efecto sombreado (turquesa en el centro oscureci\u00e9ndose hacia los bordes) Correa: Caucho negro integrado con pespuntes turquesa y cierre desplegable de acero Movimiento: OMEGA Co-Axial Master [&hellip;]<\/p>\n","protected":false},"featured_media":209626,"template":"","meta":{"advanced_seo_description":"","jetpack_seo_html_title":"","jetpack_seo_noindex":false,"jetpack_seo_schema_type":""},"product_brand":[],"product_cat":[2276],"product_tag":[2289],"berocket_brand":[],"woo-feed-brand":[],"class_list":["post-123607","product","type-product","status-publish","has-post-thumbnail","product_cat-omega-es","product_tag-seamaster-es","first","instock","sale","taxable","shipping-taxable","purchasable","product-type-simple"],"bundled_by":[],"bundle_stock_status":"instock","bundle_stock_quantity":1,"bundle_virtual":false,"bundle_layout":"","bundle_add_to_cart_form_location":"","bundle_editable_in_cart":false,"bundle_sold_individually_context":"","bundle_item_grouping":"","bundle_min_size":"","bundle_max_size":"","bundle_price":[],"bundled_items":[],"bundle_sell_ids":[],"group_of_quantity":0,"min_quantity":0,"max_quantity":"","exclude_order_quantity_value_rules":"no","exclude_category_quantity_rules":"no","combine_variations":"no","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/watchdeluxe.it\/es\/wp-json\/wp\/v2\/product\/123607","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/watchdeluxe.it\/es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/watchdeluxe.it\/es\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/watchdeluxe.it\/es\/wp-json\/wp\/v2\/media\/209626"}],"wp:attachment":[{"href":"https:\/\/watchdeluxe.it\/es\/wp-json\/wp\/v2\/media?parent=123607"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/watchdeluxe.it\/es\/wp-json\/wp\/v2\/product_brand?post=123607"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/watchdeluxe.it\/es\/wp-json\/wp\/v2\/product_cat?post=123607"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/watchdeluxe.it\/es\/wp-json\/wp\/v2\/product_tag?post=123607"},{"taxonomy":"berocket_brand","embeddable":true,"href":"https:\/\/watchdeluxe.it\/es\/wp-json\/wp\/v2\/berocket_brand?post=123607"},{"taxonomy":"woo-feed-brand","embeddable":true,"href":"https:\/\/watchdeluxe.it\/es\/wp-json\/wp\/v2\/woo-feed-brand?post=123607"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}