{"id":84412,"date":"2023-10-02T17:01:23","date_gmt":"2023-10-02T15:01:23","guid":{"rendered":"https:\/\/watchdeluxe.it\/prodotto\/longines-spirit-zulu-time-42-mm-ref-l38125536\/"},"modified":"2026-06-08T11:11:00","modified_gmt":"2026-06-08T09:11:00","slug":"longines-spirit-zulu-time-42-mm-ref-l38125536","status":"publish","type":"product","link":"https:\/\/watchdeluxe.it\/en\/prodotto\/longines-spirit-zulu-time-42-mm-ref-l38125536\/","title":{"rendered":"Longines Spirit Zulu Time 42 mm Ref. L38125536"},"content":{"rendered":"<p>Longines Spirit Zulu Time 42 mm Ref. L38125536<\/p>\n<table class=\"data-table\">\n<tbody>\n<tr class=\"even\">\n<td class=\"spec-name\">Collection<\/td>\n<td class=\"spec-value\">Spirit<\/td>\n<\/tr>\n<tr class=\"odd\">\n<td class=\"spec-name\">Complication<\/td>\n<td class=\"spec-value\">DUAL TIME<\/td>\n<\/tr>\n<tr class=\"even\">\n<td class=\"spec-name\">Movement<\/td>\n<td class=\"spec-value\">AUTOMATIC<\/td>\n<\/tr>\n<tr class=\"odd\">\n<td class=\"spec-name\">Date window<\/td>\n<td class=\"spec-value\">DATE<\/td>\n<\/tr>\n<tr class=\"even\">\n<td class=\"spec-name\">Caliber<\/td>\n<td class=\"spec-value\">L844.4<\/td>\n<\/tr>\n<tr class=\"odd\">\n<td class=\"spec-name\">Shape<\/td>\n<td class=\"spec-value\">ROUND<\/td>\n<\/tr>\n<tr class=\"even\">\n<td class=\"spec-name\">Size<\/td>\n<td class=\"spec-value\">42 MM<\/td>\n<\/tr>\n<tr class=\"odd\">\n<td class=\"spec-name\">Case Material<\/td>\n<td class=\"spec-value\">Stainless Steel and 18K Yellow Gold<\/td>\n<\/tr>\n<tr class=\"even\">\n<td class=\"spec-name\">Glass type<\/td>\n<td class=\"spec-value\">SAPPHIRE<\/td>\n<\/tr>\n<tr class=\"odd\">\n<td class=\"spec-name\">Dial<\/td>\n<td class=\"spec-value\">ANTHRACITE<\/td>\n<\/tr>\n<tr class=\"even\">\n<td class=\"spec-name\">Bracelet<\/td>\n<td class=\"spec-value\">STEEL<\/td>\n<\/tr>\n<tr class=\"odd\">\n<td class=\"spec-name\">Waterproofing<\/td>\n<td class=\"spec-value\">100 M<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n","protected":false},"excerpt":{"rendered":"<p>Longines Spirit Zulu Time 42 mm Ref. L38125536 Collection Spirit Complication DUAL TIME Movement AUTOMATIC Date window DATE Caliber L844.4 Shape ROUND Size 42 MM Case Material Stainless Steel and 18K Yellow Gold Glass type SAPPHIRE Dial ANTHRACITE Bracelet STEEL Waterproofing 100 M<\/p>\n","protected":false},"featured_media":189833,"template":"","meta":{"advanced_seo_description":"","jetpack_seo_html_title":"","jetpack_seo_noindex":false,"jetpack_seo_schema_type":""},"product_brand":[],"product_cat":[2191],"product_tag":[2409],"berocket_brand":[],"woo-feed-brand":[],"class_list":["post-84412","product","type-product","status-publish","has-post-thumbnail","product_cat-longines-en","product_tag-spirit-en","first","instock","sale","taxable","shipping-taxable","purchasable","product-type-simple"],"bundled_by":[],"bundle_stock_status":"instock","bundle_stock_quantity":1,"bundle_virtual":false,"bundle_layout":"","bundle_add_to_cart_form_location":"","bundle_editable_in_cart":false,"bundle_sold_individually_context":"","bundle_item_grouping":"","bundle_min_size":"","bundle_max_size":"","bundle_price":[],"bundled_items":[],"bundle_sell_ids":[],"group_of_quantity":0,"min_quantity":0,"max_quantity":"","exclude_order_quantity_value_rules":"no","exclude_category_quantity_rules":"no","combine_variations":"no","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/watchdeluxe.it\/en\/wp-json\/wp\/v2\/product\/84412","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/watchdeluxe.it\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/watchdeluxe.it\/en\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/watchdeluxe.it\/en\/wp-json\/wp\/v2\/media\/189833"}],"wp:attachment":[{"href":"https:\/\/watchdeluxe.it\/en\/wp-json\/wp\/v2\/media?parent=84412"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/watchdeluxe.it\/en\/wp-json\/wp\/v2\/product_brand?post=84412"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/watchdeluxe.it\/en\/wp-json\/wp\/v2\/product_cat?post=84412"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/watchdeluxe.it\/en\/wp-json\/wp\/v2\/product_tag?post=84412"},{"taxonomy":"berocket_brand","embeddable":true,"href":"https:\/\/watchdeluxe.it\/en\/wp-json\/wp\/v2\/berocket_brand?post=84412"},{"taxonomy":"woo-feed-brand","embeddable":true,"href":"https:\/\/watchdeluxe.it\/en\/wp-json\/wp\/v2\/woo-feed-brand?post=84412"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}